{"id":9411,"date":"2019-05-28T09:55:43","date_gmt":"2019-05-28T09:55:43","guid":{"rendered":"https:\/\/start.cargoclix.com\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/"},"modified":"2019-05-28T09:57:07","modified_gmt":"2019-05-28T09:57:07","slug":"marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/","title":{"rendered":"Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Non appena viene apportata una modifica nello stato del processo di una prenotazione facente parte della stessa catena, per tutte le altre prenotazioni risulta in automatico corretta la stessa marca temporale. Ad esempio se lo stato <\/span><i><span style=\"font-weight: 400;\">&#8220;Registrazione al gate&#8221; <\/span><\/i><span style=\"font-weight: 400;\">\u00e8 stato impostato per una prenotazione della catena, esso viene impostato automaticamente anche per tutte le prenotazioni della catena.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 una funzione utile per il gestore del CargoMarket: si risparmia tempo, si evitano gli ulteriori clic, inoltre la valutazione delle prenotazioni a catena diventa ancora pi\u00f9 precisa.<\/span><\/p>\n<p><strong>Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019amministratore del CargoMarket definisce quali stati del processo devono essere concatenati per ogni rampa: <\/span><i><span style=\"font-weight: 400;\"><a href=\"http:\/\/www2.cargoclix.com\/\" target=\"_blank\" rel=\"noopener\">Mio Cargoclix<\/a> &gt; Fasce orarie &gt; Rampe &gt; [Selezioni rampa] &gt; Dati di prenotazione &gt; <\/span><\/i><span style=\"font-weight: 400;\">Impostazioni del campo <\/span><i><span style=\"font-weight: 400;\">&#8220;Prenotazioni a catena&#8221; &gt; &#8220;Aggiungere&#8221; &gt; \u201cStato della catena\u201d.<\/span><\/i><span style=\"font-weight: 400;\"> Qui l&#8217;amministratore seleziona la casella dello stato del processo desiderato (ad esempio <\/span><i><span style=\"font-weight: 400;\">\u201cRegistrazione\u201d<\/span><\/i><span style=\"font-weight: 400;\"> e <\/span><i><span style=\"font-weight: 400;\">\u201cPartenza\u201d<\/span><\/i><span style=\"font-weight: 400;\">).<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-9402\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\" alt=\"Booking Data\" width=\"300\" height=\"142\" srcset=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png 300w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-768x363.png 768w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-1024x484.png 1024w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-565x267.png 565w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/05\/Booking-Data2.png 1131w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non appena viene apportata una modifica nello stato del processo di una prenotazione facente parte della stessa catena, per tutte le altre prenotazioni risulta in automatico corretta la stessa marca temporale. Ad esempio se lo stato &#8220;Registrazione al gate&#8221; \u00e8 stato impostato per una prenotazione della catena, esso viene impostato automaticamente anche per tutte le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[308],"tags":[263,267],"class_list":["post-9411","post","type-post","status-publish","format-standard","hentry","category-tech-news-it","tag-slot-2-de-it","tag-tech-news-2-de-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Non appena viene apportata una modifica nello stato del processo di una prenotazione facente parte della stessa catena, per tutte le altre prenotazioni risulta in automatico corretta la stessa marca temporale. Ad esempio se lo stato &#8220;Registrazione al gate&#8221; \u00e8 stato impostato per una prenotazione della catena, esso viene impostato automaticamente anche per tutte le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-28T09:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-28T09:57:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena\",\"datePublished\":\"2019-05-28T09:55:43+00:00\",\"dateModified\":\"2019-05-28T09:57:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\"},\"wordCount\":167,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\",\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\",\"url\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\",\"name\":\"Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\",\"datePublished\":\"2019-05-28T09:55:43+00:00\",\"dateModified\":\"2019-05-28T09:57:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage\",\"url\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\",\"contentUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/safe-checkin.com\/it\/category\/tech-news-it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/it\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/","og_locale":"it_IT","og_type":"article","og_title":"Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix","og_description":"Non appena viene apportata una modifica nello stato del processo di una prenotazione facente parte della stessa catena, per tutte le altre prenotazioni risulta in automatico corretta la stessa marca temporale. Ad esempio se lo stato &#8220;Registrazione al gate&#8221; \u00e8 stato impostato per una prenotazione della catena, esso viene impostato automaticamente anche per tutte le [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-05-28T09:55:43+00:00","article_modified_time":"2019-05-28T09:57:07+00:00","og_image":[{"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png","type":"","width":"","height":""}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"websitedev","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena","datePublished":"2019-05-28T09:55:43+00:00","dateModified":"2019-05-28T09:57:07+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/"},"wordCount":167,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"image":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png","keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/","url":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/","name":"Marca temporale simultanea per tutte le prenotazioni a catena - Stato della catena - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage"},"image":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png","datePublished":"2019-05-28T09:55:43+00:00","dateModified":"2019-05-28T09:57:07+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#primaryimage","url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png","contentUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/05\/Booking-Data2-300x142.png"},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/it\/2019\/05\/28\/marca-temporale-simultanea-per-tutte-le-prenotazioni-a-catena-stato-della-catena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/it\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/safe-checkin.com\/it\/category\/tech-news-it\/"},{"@type":"ListItem","position":3,"name":"Marca temporale simultanea per tutte le prenotazioni a catena &#8211; Stato della catena"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/it\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts\/9411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/comments?post=9411"}],"version-history":[{"count":1,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts\/9411\/revisions"}],"predecessor-version":[{"id":9412,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts\/9411\/revisions\/9412"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/media?parent=9411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/categories?post=9411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/tags?post=9411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}