{"id":18566,"date":"2022-08-05T12:25:54","date_gmt":"2022-08-05T12:25:54","guid":{"rendered":"https:\/\/start.cargoclix.com\/2022\/08\/05\/siemens-leipzig-implementa-slot\/"},"modified":"2022-08-05T12:25:54","modified_gmt":"2022-08-05T12:25:54","slug":"siemens-leipzig-implementa-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/","title":{"rendered":"Siemens Leipzig implementa SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Siemens AG Leipzig lavora con il sistema informatico <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> di Cargoclix. Grazie alla soluzione viene assicurata una gestione senza ingorghi di circa 20 camion al giorno nelle aree merci in entrata ed in uscita. Si paga 0,50 euro a prenotazione. Le prenotazioni possono essere effettuate gi\u00e0 14 giorni in anticipo rispetto alla data desiderata. La data ultima \u00e8 tre ore prima della fascia oraria desiderata.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La multinazionale Siemens si concentra sui settori dell&#8217;industria, delle infrastrutture, della mobilit\u00e0 e della salute. Nell&#8217;anno fiscale 2021, conclusosi il 30 settembre 2021, il Gruppo Siemens ha registrato un fatturato di 62,3 miliardi di euro e un utile al netto delle imposte di 6,7 miliardi di euro. Al 30 settembre 2021, l&#8217;azienda contava circa 303.000 dipendenti in tutto il mondo.<\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/it\/slot\/\"><span style=\"font-weight: 400;\">* Cargoclix <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\">. Gestione delle fasce orarie e dello yard<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> ottimizza i processi e l\u2019impiego del personale presso la rampa, previene i tempi di attesa ed i picchi di carico presso i punti di carico e scarico. Cargoclix <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> offre trasparenza su tutti i processi logistici ed \u00e8 la migliore soluzione per l\u2019industria, il commercio, i fornitori di servizi logistici e le aziende di trasporto.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siemens AG Leipzig lavora con il sistema informatico SLOT di Cargoclix. Grazie alla soluzione viene assicurata una gestione senza ingorghi di circa 20 camion al giorno nelle aree merci in entrata ed in uscita. Si paga 0,50 euro a prenotazione. Le prenotazioni possono essere effettuate gi\u00e0 14 giorni in anticipo rispetto alla data desiderata. La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[294],"tags":[263],"class_list":["post-18566","post","type-post","status-publish","format-standard","hentry","category-slot-news-it","tag-slot-2-de-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siemens Leipzig implementa SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siemens Leipzig implementa SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Siemens AG Leipzig lavora con il sistema informatico SLOT di Cargoclix. Grazie alla soluzione viene assicurata una gestione senza ingorghi di circa 20 camion al giorno nelle aree merci in entrata ed in uscita. Si paga 0,50 euro a prenotazione. Le prenotazioni possono essere effettuate gi\u00e0 14 giorni in anticipo rispetto alla data desiderata. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-05T12:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Siemens Leipzig implementa SLOT\",\"datePublished\":\"2022-08-05T12:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"SLOT News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\",\"url\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\",\"name\":\"Siemens Leipzig implementa SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2022-08-05T12:25:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/slot-news-de\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Siemens Leipzig implementa SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/it\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siemens Leipzig implementa SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/","og_locale":"it_IT","og_type":"article","og_title":"Siemens Leipzig implementa SLOT - Cargoclix","og_description":"Siemens AG Leipzig lavora con il sistema informatico SLOT di Cargoclix. Grazie alla soluzione viene assicurata una gestione senza ingorghi di circa 20 camion al giorno nelle aree merci in entrata ed in uscita. Si paga 0,50 euro a prenotazione. Le prenotazioni possono essere effettuate gi\u00e0 14 giorni in anticipo rispetto alla data desiderata. La [&hellip;]","og_url":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2022-08-05T12:25:54+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"websitedev","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#article","isPartOf":{"@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Siemens Leipzig implementa SLOT","datePublished":"2022-08-05T12:25:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/"},"wordCount":184,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["SLOT News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/","url":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/","name":"Siemens Leipzig implementa SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2022-08-05T12:25:54+00:00","breadcrumb":{"@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mail.savoiedecision.com\/it\/2022\/08\/05\/siemens-leipzig-implementa-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/it\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/slot-news-de\/"},{"@type":"ListItem","position":4,"name":"Siemens Leipzig implementa SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/it\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts\/18566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/comments?post=18566"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/posts\/18566\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/media?parent=18566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/categories?post=18566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/it\/wp-json\/wp\/v2\/tags?post=18566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}