{"id":8372,"date":"2019-02-06T13:53:37","date_gmt":"2019-02-06T13:53:37","guid":{"rendered":"https:\/\/start.cargoclix.com\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/"},"modified":"2019-02-06T13:53:37","modified_gmt":"2019-02-06T13:53:37","slug":"reservation-en-serie-pour-les-transporteurs","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/","title":{"rendered":"R\u00e9servation en s\u00e9rie pour les transporteurs"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Les r\u00e9servations en s\u00e9rie peuvent d\u00e9sormais \u00eatre sauvegard\u00e9es par les transporteurs. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 activ\u00e9e dans Cargoclix conform\u00e9ment aux demandes des clients. Cette fonctionnalit\u00e9 inclut la possibilit\u00e9 de sauvegarder les r\u00e9servations en s\u00e9rie pour les utilisateurs avec certains droits (Carrier ou Carrier 2) et non pour un utilisateur sp\u00e9cifique. Gr\u00e2ce \u00e0 cette nouvelle fonctionnalit\u00e9, les fournisseurs de services peuvent planifier des rendez-vous \u00a0r\u00e9p\u00e9titifs en un seul clic, m\u00eame si une r\u00e9servation en s\u00e9rie ne se r\u00e9p\u00e8te que dans un avenir lointain. Les r\u00e9servations en s\u00e9rie peuvent \u00eatre rapidement mises \u00e0 jour en un seul clic. Avantage: gr\u00e2ce \u00e0 cette nouvelle fonctionnalit\u00e9, les clients ne sont plus oblig\u00e9s d&rsquo;effectuer des r\u00e9servations en s\u00e9rie pour les transporteurs.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9servations en s\u00e9rie peuvent d\u00e9sormais \u00eatre sauvegard\u00e9es par les transporteurs. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 activ\u00e9e dans Cargoclix conform\u00e9ment aux demandes des clients. Cette fonctionnalit\u00e9 inclut la possibilit\u00e9 de sauvegarder les r\u00e9servations en s\u00e9rie pour les utilisateurs avec certains droits (Carrier ou Carrier 2) et non pour un utilisateur sp\u00e9cifique. Gr\u00e2ce \u00e0 cette nouvelle fonctionnalit\u00e9, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[310],"tags":[262,268],"class_list":["post-8372","post","type-post","status-publish","format-standard","hentry","category-tech-news-fr","tag-slot-2-de-fr","tag-tech-news-2-de-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9servations en s\u00e9rie peuvent d\u00e9sormais \u00eatre sauvegard\u00e9es par les transporteurs. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 activ\u00e9e dans Cargoclix conform\u00e9ment aux demandes des clients. Cette fonctionnalit\u00e9 inclut la possibilit\u00e9 de sauvegarder les r\u00e9servations en s\u00e9rie pour les utilisateurs avec certains droits (Carrier ou Carrier 2) et non pour un utilisateur sp\u00e9cifique. Gr\u00e2ce \u00e0 cette nouvelle fonctionnalit\u00e9, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-06T13:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"R\u00e9servation en s\u00e9rie pour les transporteurs\",\"datePublished\":\"2019-02-06T13:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\",\"url\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\",\"name\":\"R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2019-02-06T13:53:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/safe-checkin.com\/fr\/category\/tech-news-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9servation en s\u00e9rie pour les transporteurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix","og_description":"Les r\u00e9servations en s\u00e9rie peuvent d\u00e9sormais \u00eatre sauvegard\u00e9es par les transporteurs. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 activ\u00e9e dans Cargoclix conform\u00e9ment aux demandes des clients. Cette fonctionnalit\u00e9 inclut la possibilit\u00e9 de sauvegarder les r\u00e9servations en s\u00e9rie pour les utilisateurs avec certains droits (Carrier ou Carrier 2) et non pour un utilisateur sp\u00e9cifique. Gr\u00e2ce \u00e0 cette nouvelle fonctionnalit\u00e9, [&hellip;]","og_url":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-02-06T13:53:37+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"websitedev","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#article","isPartOf":{"@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"R\u00e9servation en s\u00e9rie pour les transporteurs","datePublished":"2019-02-06T13:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/"},"wordCount":143,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/","url":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/","name":"R\u00e9servation en s\u00e9rie pour les transporteurs - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2019-02-06T13:53:37+00:00","breadcrumb":{"@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mail.savoiedecision.com\/fr\/2019\/02\/06\/reservation-en-serie-pour-les-transporteurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/fr\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/safe-checkin.com\/fr\/category\/tech-news-fr\/"},{"@type":"ListItem","position":3,"name":"R\u00e9servation en s\u00e9rie pour les transporteurs"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/8372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/comments?post=8372"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/8372\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/media?parent=8372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/categories?post=8372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/tags?post=8372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}