{"id":8215,"date":"2019-01-21T12:02:35","date_gmt":"2019-01-21T12:02:35","guid":{"rendered":"https:\/\/start.cargoclix.com\/2019\/01\/18\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/"},"modified":"2020-07-09T15:36:30","modified_gmt":"2020-07-09T15:36:30","slug":"wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/","title":{"rendered":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix"},"content":{"rendered":"<div id=\"attachment_8200\" style=\"width: 310px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-8200\" class=\"wp-image-8200 size-medium\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/01\/wuerth-300x225.jpg\" alt=\"(Photo: Service W\u00fcrth Industrie)\" width=\"300\" height=\"225\" srcset=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-300x225.jpg 300w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-768x576.jpg 768w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-1024x768.jpg 1024w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-800x600.jpg 800w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-8200\" class=\"wp-caption-text\"><span style=\"font-weight: 400;\">Centre logistique d&rsquo;approvisionnement industriel \u00e0 Bad Mergentheim<\/span><\/p><\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">D\u00e9ploiement du SLOT dans l&rsquo;entrep\u00f4t central europ\u00e9en de W\u00fcrth Industrie Service \u00e0 Bad Mergentheim.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Dix ans de gestion des cr\u00e9neaux horaires \u00a0au sein du groupe W\u00fcrth<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">(Freiburg i.B., 7.1.2019) Le service W\u00fcrth Industrie introduit le syst\u00e8me de gestion des cr\u00e9neaux horaires sur le site de Bad Mergentheim. \u00c0 partir de janvier, le syst\u00e8me en ligne SLOT de la soci\u00e9t\u00e9 de logiciel Cargoclix, bas\u00e9e \u00e0 Fribourg, y sera utilis\u00e9 pour optimiser le contr\u00f4le des flux entrants pour la gamme de pi\u00e8ces C. L&rsquo;objectif est d&rsquo;\u00e9viter les fluctuations du volume des marchandises entrantes et de r\u00e9partir le nombre de palettes entrantes de mani\u00e8re uniforme tout au long de la semaine. Ainsi que, l&rsquo;entreprise souhaite r\u00e9duire le temps d&rsquo;inactivit\u00e9 des fournisseurs de services.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00ab\u00a0Au sein du groupe W\u00fcrth, nous avons eu la meilleure exp\u00e9rience en mati\u00e8re de gestion des cr\u00e9neaux horaires et en termes de transparence et de s\u00e9curit\u00e9 de la planification. C\u2019est pourquoi d\u00e8s le d\u00e9marrage du syst\u00e8me nous \u00e9tions s\u00fbrs de l&rsquo;utilisation r\u00e9guli\u00e8re de SLOT pour l&rsquo;optimisation des flux des marchandises entrantes et pour la r\u00e9duction sensible du temps d\u2019inactivit\u00e9 pour les prestataires de services logistiques.\u00a0\u00bb<\/span><span style=\"font-weight: 400;\">,<\/span> <span style=\"font-weight: 400;\">d\u00e9clare Helmut Ayzenkolb, responsable de la logistique et membre de l&rsquo;\u00e9quipe de direction de W\u00fcrth Industrie Service \u00e0 Bad Mergentheim.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix a \u00e9t\u00e9 choisi parce que \u00ab\u00a0le syst\u00e8me en ligne SLOT est utilis\u00e9 avec succ\u00e8s par le groupe W\u00fcrth depuis dix ans et qu&rsquo;il est \u00e9galement standard dans le secteur de transports\u00a0\u00bb, ajoute Eisenkolb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La soci\u00e9t\u00e9 W\u00fcrth Industrie Service, l\u2019un des plus grands sites de W\u00fcrth, a opt\u00e9 pour le syst\u00e8me SLOT. Dans l&rsquo;entrep\u00f4t central europ\u00e9en de la filiale Adolf W\u00fcrth, l&rsquo;ensemble des besoins en pi\u00e8ces C de plus de 20.000 clients est g\u00e9r\u00e9 sur 55.000 m\u00e8tres carr\u00e9s.<\/span> <span style=\"font-weight: 400;\">Le d\u00e9partement logistique emploie \u00e0 lui seul 450 personnes. Une gamme sp\u00e9cialis\u00e9e de plus de 1.000.000 articles constitue la base du traitement industriel des pi\u00e8ces C. Outre les pi\u00e8ces DIN ainsi que les \u00e9l\u00e9ments de connexion et de fixation, la gamme de produits comprend \u00e9galement des pi\u00e8ces sp\u00e9ciales et des pi\u00e8ces de dessin adapt\u00e9es aux besoins des clients, ainsi que des accessoires et mat\u00e9riel d&rsquo;exploitation.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chaque jour, environ les 35 camions arrivent sur les 10 quais de r\u00e9ception des marchandises. Ils sont d\u00e9charg\u00e9s, les marchandises sont s\u00e9lectionn\u00e9s, stock\u00e9es, emball\u00e9es et exp\u00e9di\u00e9es directement aux clients.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">W\u00fcrth Industrie Service organise de sa propre initiative la collecte aupr\u00e8s de 80% de ses fournisseurs, dont le 20% la soci\u00e9t\u00e9 livre gratuitement. La r\u00e9servation des cr\u00e9neaux horaires est possible via SLOT \u00e0 partir du moment de la commande. Les exp\u00e9diteurs ind\u00e9pendants peuvent r\u00e9server 30 jours avant le d\u00e9marrage du cr\u00e9neau et la r\u00e9servation peut \u00eatre manipul\u00e9e ou bien supprim\u00e9e cinq heures avant la livraison pr\u00e9vue. Le montant de chaque r\u00e9servation est 50 centimes d&rsquo;euros. La r\u00e9servation du cr\u00e9neau n&rsquo;est pas obligatoire, mais toute personne qui livre sans avoir r\u00e9serv\u00e9 un cr\u00e9neau doit respecter les d\u00e9lais d&rsquo;attente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le groupe W\u00fcrth est consid\u00e9r\u00e9 comme un pionnier dans la gestion des cr\u00e9neaux horaires et pratiquement aucune autre soci\u00e9t\u00e9 n\u2019a autant d\u2019exp\u00e9rience dans la gestion moderne des quais. Adolf W\u00fcrth GmbH &amp; Co. KG a commenc\u00e9 ses activit\u00e9s en 2009 avec l&rsquo;utilisation de Cargoclix SLOT \u00e0 K\u00fcnzelsau. Parall\u00e8lement, toute une s\u00e9rie de mesures d&rsquo;accompagnement ont \u00e9t\u00e9 mises en \u0153uvre, notamment un code de conduite pour les chauffeurs routiers. Mais il comprend \u00e9galement des salles de bains modernes et des salles de repos avec Internet et t\u00e9l\u00e9vision ou un parking surveill\u00e9 pour les conducteurs. Depuis lors, de nombreux sites situ\u00e9s \u00e0 Wurth en Allemagne et \u00e0 l&rsquo;\u00e9tranger sont \u00e9quip\u00e9s d&rsquo;un syst\u00e8me bas\u00e9 sur le Web.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c0 propos de Cargoclix <\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix est un march\u00e9 Internet neutre pour les appels d&rsquo;offres \u00e9lectroniques de services de transport et de logistique. Cargoclix est aussi un fournisseur de syst\u00e8me modulaire de gestion des cr\u00e9neaux horaires. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La gamme de services offerts par la plate-forme logistique \u00ab\u00a0Cargoclix TENDER\u00a0\u00bb comprend des appels d&rsquo;offres internationaux pour des contrats de transport routier, ferroviaire, a\u00e9rien, maritime et fluvial, ainsi que pour des services de messagerie express et des services de la logistiques et d&rsquo;entreposage. Avec plus de 28.000 membres inscrits issus de l&rsquo;industrie, du commerce et d&rsquo;exp\u00e9ditions, TENDER est l&rsquo;une des principales plates-formes internationales d&rsquo;appels d&rsquo;offres pour le transport et la logistique.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le produit principal de la division Gestion des cr\u00e9neaux horaires est le logiciel adaptable et modulaire \u00ab\u00a0Cargoclix SLOT\u00a0\u00bb pour l&rsquo;optimisation des processus sur les quais. Avec plus de 50.000 utilisateurs, SLOT est l\u2019un des syst\u00e8mes de gestion des cr\u00e9neaux horaires les plus largement utilis\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix est une marque de Dr. Meier &amp; Schmidt GmbH. L&rsquo;entreprise a \u00e9t\u00e9 fond\u00e9e en 1998 et actuellement elle \u00a0est bas\u00e9e \u00e0 Freiburg i.Br. <\/span><\/p>\n<p><a href=\"http:\/\/www.cargoclix.com\"><span style=\"font-weight: 400;\">www.cargoclix.com<\/span><\/a><\/p>\n<p><strong>\u00c0 propos de W\u00fcrth Industrie Service <\/strong><\/p>\n<p><span style=\"font-weight: 400;\">W\u00fcrth Industrie Service GmbH &amp; Co. KG est un partenaire de pi\u00e8ces C dans le secteur de fabrication. Avec des solutions d&rsquo;approvisionnement sur mesure, la soci\u00e9t\u00e9 fournit automatiquement \u00e0 ses clients des \u00e9l\u00e9ments de connexion et de fixation, \u00a0ainsi que des \u00e9quipements auxiliaires et des mat\u00e9riaux d&rsquo;exploitation.W\u00fcrth Industrie est une filiale ind\u00e9pendante de Adolf W\u00fcrth GmbH &amp; Co. KG, K\u00fcnzelsau, Allemagne.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nous serions heureux de recevoir un exemplaire!<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Pour toute question veuillez contacter:<\/strong> CARGOCLIX &#8211; Dr. Meier &amp; Schmidt GmbH Johannes Schmidt, M\u00fcnsterplatz 11 \/ \u00e0 \u00a0Kornhaus, D-79098 Freiburg i.Br.,<\/span><\/p>\n<p><span style=\"font-weight: 400;\">T\u00e9l: +49 (0) 761\/20 55 11 &#8211; 02<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E-mail: <\/span><a href=\"mailto:presse@cargoclix.com\"><span style=\"font-weight: 400;\">presse@cargoclix.com<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; D\u00e9ploiement du SLOT dans l&rsquo;entrep\u00f4t central europ\u00e9en de W\u00fcrth Industrie Service \u00e0 Bad Mergentheim. Dix ans de gestion des cr\u00e9neaux horaires \u00a0au sein du groupe W\u00fcrth (Freiburg i.B., 7.1.2019) Le service W\u00fcrth Industrie introduit le syst\u00e8me de gestion des cr\u00e9neaux horaires sur le site de Bad Mergentheim. \u00c0 partir de janvier, le syst\u00e8me en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[323],"tags":[262],"class_list":["post-8215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases-fr","tag-slot-2-de-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"&nbsp; D\u00e9ploiement du SLOT dans l&rsquo;entrep\u00f4t central europ\u00e9en de W\u00fcrth Industrie Service \u00e0 Bad Mergentheim. Dix ans de gestion des cr\u00e9neaux horaires \u00a0au sein du groupe W\u00fcrth (Freiburg i.B., 7.1.2019) Le service W\u00fcrth Industrie introduit le syst\u00e8me de gestion des cr\u00e9neaux horaires sur le site de Bad Mergentheim. \u00c0 partir de janvier, le syst\u00e8me en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-21T12:02:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-09T15:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png\" \/>\n\t<meta property=\"og:image:width\" content=\"996\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix\",\"datePublished\":\"2019-01-21T12:02:35+00:00\",\"dateModified\":\"2020-07-09T15:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\"},\"wordCount\":1004,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png\",\"keywords\":[\"SLOT\"],\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\",\"url\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\",\"name\":\"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png\",\"datePublished\":\"2019-01-21T12:02:35+00:00\",\"dateModified\":\"2020-07-09T15:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage\",\"url\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png\",\"contentUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png\",\"width\":996,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\/\/cargoclix.info\/fr\/category\/press-releases-fr\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/","og_locale":"fr_FR","og_type":"article","og_title":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix","og_description":"&nbsp; D\u00e9ploiement du SLOT dans l&rsquo;entrep\u00f4t central europ\u00e9en de W\u00fcrth Industrie Service \u00e0 Bad Mergentheim. Dix ans de gestion des cr\u00e9neaux horaires \u00a0au sein du groupe W\u00fcrth (Freiburg i.B., 7.1.2019) Le service W\u00fcrth Industrie introduit le syst\u00e8me de gestion des cr\u00e9neaux horaires sur le site de Bad Mergentheim. \u00c0 partir de janvier, le syst\u00e8me en [&hellip;]","og_url":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-01-21T12:02:35+00:00","article_modified_time":"2020-07-09T15:36:30+00:00","og_image":[{"width":996,"height":660,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"websitedev","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#article","isPartOf":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix","datePublished":"2019-01-21T12:02:35+00:00","dateModified":"2020-07-09T15:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/"},"wordCount":1004,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"image":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage"},"thumbnailUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png","keywords":["SLOT"],"articleSection":["Press Releases"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/","url":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/","name":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage"},"image":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage"},"thumbnailUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png","datePublished":"2019-01-21T12:02:35+00:00","dateModified":"2020-07-09T15:36:30+00:00","breadcrumb":{"@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#primaryimage","url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png","contentUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/01\/wuerth-e1592986839644.png","width":996,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/safe-checkin.com\/fr\/2019\/01\/21\/wurth-industrie-service-presente-le-systeme-de-gestion-des-creneaux-horaires-cargoclix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/cargoclix.info\/fr\/category\/press-releases-fr\/"},{"@type":"ListItem","position":3,"name":"W\u00fcrth Industrie Service pr\u00e9sente le syst\u00e8me de gestion des cr\u00e9neaux horaires Cargoclix"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/8215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/comments?post=8215"}],"version-history":[{"count":2,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/8215\/revisions"}],"predecessor-version":[{"id":8217,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/8215\/revisions\/8217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/media\/13471"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/media?parent=8215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/categories?post=8215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/tags?post=8215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}