{"id":17984,"date":"2022-01-25T15:35:36","date_gmt":"2022-01-25T15:35:36","guid":{"rendered":"https:\/\/start.cargoclix.com\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/"},"modified":"2022-01-25T15:41:13","modified_gmt":"2022-01-25T15:41:13","slug":"zumtobel-gives-green-light-to-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/","title":{"rendered":"Zumtobel donne le feu vert \u00e0 SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">L&rsquo;entreprise d&rsquo;\u00e9clairage Zumtobel de Dornbirn en Autriche a introduit sur son site de Hohenems le syst\u00e8me de gestion des cr\u00e9neaux horaires SLOT de Cargoclix bas\u00e9 sur le cloud et optimise ainsi le traitement quotidien sans embouteillage d&rsquo;environ 15 camions \u00e0 la r\u00e9ception des marchandises. Les prestataires logistiques qui souhaitent y r\u00e9server un cr\u00e9neau horaire pour la livraison peuvent le faire avec un pr\u00e9avis de dix jours. La possibilit\u00e9 de r\u00e9servation la plus tardive est de douze heures avant la date souhait\u00e9e. Les frais de r\u00e9servation par cr\u00e9neau horaire s&rsquo;\u00e9l\u00e8vent \u00e0 50 centimes. Ils sont pris en charge par les prestataires logistiques.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zumtobel propose le d\u00e9veloppement, la fabrication et la distribution de techniques d&rsquo;\u00e9clairage ainsi que de solutions et de composants d&rsquo;\u00e9clairage pour diff\u00e9rents domaines d&rsquo;application. L&rsquo;entreprise collabore avec plus de 90 bureaux de vente et partenaires dans le monde entier et emploie environ 5.800 personnes.\u00a0 <\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/fr\/slot\/\"><span style=\"font-weight: 400;\">*Cargoclix SLOT. Gestion des cr\u00e9neaux horaires et d\u2019enr\u00e9gistrement<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT aide \u00e0 optimiser les processus et le d\u00e9ploiement du personnel sur les quais. SLOT vous aide d\u2019\u00e9viter des temps d\u2019attentes et les pics de charge de travail aux points de chargement et de d\u00e9chargement. Notre syst\u00e8me de gestion des cr\u00e9neaux horaires assure \u00e9galement la transparence de tous les processus logistiques repr\u00e9sent\u00e9s. C\u2019est donc la meilleure solution pour l\u2019industrie, le commerce, les prestataires de services logistiques et les entreprises de transport.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entreprise d&rsquo;\u00e9clairage Zumtobel de Dornbirn en Autriche a introduit sur son site de Hohenems le syst\u00e8me de gestion des cr\u00e9neaux horaires SLOT de Cargoclix bas\u00e9 sur le cloud et optimise ainsi le traitement quotidien sans embouteillage d&rsquo;environ 15 camions \u00e0 la r\u00e9ception des marchandises. Les prestataires logistiques qui souhaitent y r\u00e9server un cr\u00e9neau horaire pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[330,295],"tags":[262],"class_list":["post-17984","post","type-post","status-publish","format-standard","hentry","category-company-news-fr","category-slot-news-fr","tag-slot-2-de-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entreprise d&rsquo;\u00e9clairage Zumtobel de Dornbirn en Autriche a introduit sur son site de Hohenems le syst\u00e8me de gestion des cr\u00e9neaux horaires SLOT de Cargoclix bas\u00e9 sur le cloud et optimise ainsi le traitement quotidien sans embouteillage d&rsquo;environ 15 camions \u00e0 la r\u00e9ception des marchandises. Les prestataires logistiques qui souhaitent y r\u00e9server un cr\u00e9neau horaire pour [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T15:35:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-25T15:41:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Zumtobel donne le feu vert \u00e0 SLOT\",\"datePublished\":\"2022-01-25T15:35:36+00:00\",\"dateModified\":\"2022-01-25T15:41:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\"},\"wordCount\":254,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\",\"url\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\",\"name\":\"Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2022-01-25T15:35:36+00:00\",\"dateModified\":\"2022-01-25T15:41:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/82.165.97.253\/category\/company-news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/safe-checkin.com\/category\/company-news\/slot-news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Zumtobel donne le feu vert \u00e0 SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/","og_locale":"fr_FR","og_type":"article","og_title":"Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix","og_description":"L&rsquo;entreprise d&rsquo;\u00e9clairage Zumtobel de Dornbirn en Autriche a introduit sur son site de Hohenems le syst\u00e8me de gestion des cr\u00e9neaux horaires SLOT de Cargoclix bas\u00e9 sur le cloud et optimise ainsi le traitement quotidien sans embouteillage d&rsquo;environ 15 camions \u00e0 la r\u00e9ception des marchandises. Les prestataires logistiques qui souhaitent y r\u00e9server un cr\u00e9neau horaire pour [&hellip;]","og_url":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2022-01-25T15:35:36+00:00","article_modified_time":"2022-01-25T15:41:13+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"websitedev","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#article","isPartOf":{"@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Zumtobel donne le feu vert \u00e0 SLOT","datePublished":"2022-01-25T15:35:36+00:00","dateModified":"2022-01-25T15:41:13+00:00","mainEntityOfPage":{"@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/"},"wordCount":254,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/","url":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/","name":"Zumtobel donne le feu vert \u00e0 SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2022-01-25T15:35:36+00:00","dateModified":"2022-01-25T15:41:13+00:00","breadcrumb":{"@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mail.savoiedecision.com\/fr\/2022\/01\/25\/zumtobel-gives-green-light-to-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/82.165.97.253\/category\/company-news\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/safe-checkin.com\/category\/company-news\/slot-news\/"},{"@type":"ListItem","position":4,"name":"Zumtobel donne le feu vert \u00e0 SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/fr\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/17984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/comments?post=17984"}],"version-history":[{"count":1,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/17984\/revisions"}],"predecessor-version":[{"id":17989,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/posts\/17984\/revisions\/17989"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/media?parent=17984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/categories?post=17984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/fr\/wp-json\/wp\/v2\/tags?post=17984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}