{"id":8377,"date":"2019-02-06T14:30:00","date_gmt":"2019-02-06T14:30:00","guid":{"rendered":"https:\/\/start.cargoclix.com\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/"},"modified":"2019-02-06T14:30:00","modified_gmt":"2019-02-06T14:30:00","slug":"carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/","title":{"rendered":"Carga de mapeo de palabras clave utilizando un archivo de Excel"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hay noticias para los clientes para los que la transferencia al programa s\u00f3lo est\u00e1 activa introduciendo una palabra clave v\u00e1lida: Hasta ahora, s\u00f3lo era posible introducir manualmente las condiciones para la transferencia (asignaci\u00f3n) mediante la interfaz de usuario. El administrador de CargoMarket ten\u00eda que hacer clic en las palabras clave para asignar rampas o para averiguar cu\u00e1les de ellas ya ten\u00edan una asignaci\u00f3n. Nuevo: El administrador de CargoMarket puede descargar un archivo de muestra y a\u00f1adir palabras clave a las rampas respectivas. Entonces puede subir el archivo. A continuaci\u00f3n, se importan todas las reglas de asignaci\u00f3n. Todo esto ayuda especialmente a los administradores de CargoMarket con grandes configuraciones para varias ubicaciones. Esto hace que el proceso sea considerablemente m\u00e1s r\u00e1pido. Los cambios en la situaci\u00f3n se pueden realizar r\u00e1pidamente con la ayuda de nuevas cargas.<\/span><\/p>\n<p><strong>Carga de mapeo de palabras clave utilizando un archivo de Excel<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Los administradores de CargoMarket pueden configurar la funci\u00f3n en: Mi Cargoclix &gt; Franjas horarias &gt;[Haga clic en el nivel de CargoMarket] &gt; General &gt; Bot\u00f3n \u00abDescargar mapa\u00bb. El archivo descargado debe rellenarse localmente en el ordenador. A continuaci\u00f3n, vuelva a cargar el archivo terminado a trav\u00e9s de Seleccionar archivo &gt; Cargar asignaci\u00f3n. Si la carga no funciona, se informa al usuario de un mensaje de error y se le dan instrucciones sobre qu\u00e9 hacer.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay noticias para los clientes para los que la transferencia al programa s\u00f3lo est\u00e1 activa introduciendo una palabra clave v\u00e1lida: Hasta ahora, s\u00f3lo era posible introducir manualmente las condiciones para la transferencia (asignaci\u00f3n) mediante la interfaz de usuario. El administrador de CargoMarket ten\u00eda que hacer clic en las palabras clave para asignar rampas o para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[309],"tags":[335,334],"class_list":["post-8377","post","type-post","status-publish","format-standard","hentry","category-tech-news-es","tag-slot","tag-tech-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Hay noticias para los clientes para los que la transferencia al programa s\u00f3lo est\u00e1 activa introduciendo una palabra clave v\u00e1lida: Hasta ahora, s\u00f3lo era posible introducir manualmente las condiciones para la transferencia (asignaci\u00f3n) mediante la interfaz de usuario. El administrador de CargoMarket ten\u00eda que hacer clic en las palabras clave para asignar rampas o para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-06T14:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Carga de mapeo de palabras clave utilizando un archivo de Excel\",\"datePublished\":\"2019-02-06T14:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\",\"url\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\",\"name\":\"Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2019-02-06T14:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/82.165.97.253\/es\/category\/tech-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carga de mapeo de palabras clave utilizando un archivo de Excel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/","og_locale":"es_ES","og_type":"article","og_title":"Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix","og_description":"Hay noticias para los clientes para los que la transferencia al programa s\u00f3lo est\u00e1 activa introduciendo una palabra clave v\u00e1lida: Hasta ahora, s\u00f3lo era posible introducir manualmente las condiciones para la transferencia (asignaci\u00f3n) mediante la interfaz de usuario. El administrador de CargoMarket ten\u00eda que hacer clic en las palabras clave para asignar rampas o para [&hellip;]","og_url":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-02-06T14:30:00+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#article","isPartOf":{"@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Carga de mapeo de palabras clave utilizando un archivo de Excel","datePublished":"2019-02-06T14:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/"},"wordCount":252,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/","url":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/","name":"Carga de mapeo de palabras clave utilizando un archivo de Excel - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2019-02-06T14:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mail.savoiedecision.com\/es\/2019\/02\/06\/carga-de-mapeo-de-palabras-clave-utilizando-un-archivo-de-excel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/es\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/82.165.97.253\/es\/category\/tech-news-es\/"},{"@type":"ListItem","position":3,"name":"Carga de mapeo de palabras clave utilizando un archivo de Excel"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/8377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/comments?post=8377"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/8377\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/media?parent=8377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/categories?post=8377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/tags?post=8377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}