{"id":7911,"date":"2018-10-31T14:23:40","date_gmt":"2018-10-31T14:23:40","guid":{"rendered":"https:\/\/www.cargoclix.com\/2018\/10\/31\/bartling-opta-por-slot\/"},"modified":"2018-10-31T14:23:40","modified_gmt":"2018-10-31T14:23:40","slug":"bartling-opta-por-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/","title":{"rendered":"Bartling opta por SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La empresa Bartling GmbH &amp; Co. KG es uno de los fabricantes m\u00e1s exitosos de envases a medida para la industria alimentaria. Para optimizar los procesos log\u00edsticos en la rampa, la empresa de Borgholzhausen conf\u00eda en la plataforma de gesti\u00f3n de franjas horarias SLOT de Cargoclix. Aproximadamente 15 camiones son cargados y descargados diariamente en la entrada y salida de mercanc\u00edas. La reserva es posible a trav\u00e9s de Internet, pero con una semana de antelaci\u00f3n y hasta las 0:00 horas del d\u00eda anterior a la franja horaria deseada. La tarifa por una horaria es 50 c\u00e9ntimos.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa Bartling GmbH &amp; Co. KG es uno de los fabricantes m\u00e1s exitosos de envases a medida para la industria alimentaria. Para optimizar los procesos log\u00edsticos en la rampa, la empresa de Borgholzhausen conf\u00eda en la plataforma de gesti\u00f3n de franjas horarias SLOT de Cargoclix. Aproximadamente 15 camiones son cargados y descargados diariamente en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[331,292],"tags":[335],"class_list":["post-7911","post","type-post","status-publish","format-standard","hentry","category-company-news-es","category-slot-news-es","tag-slot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bartling opta por SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bartling opta por SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"La empresa Bartling GmbH &amp; Co. KG es uno de los fabricantes m\u00e1s exitosos de envases a medida para la industria alimentaria. Para optimizar los procesos log\u00edsticos en la rampa, la empresa de Borgholzhausen conf\u00eda en la plataforma de gesti\u00f3n de franjas horarias SLOT de Cargoclix. Aproximadamente 15 camiones son cargados y descargados diariamente en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-31T14:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Bartling opta por SLOT\",\"datePublished\":\"2018-10-31T14:23:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\",\"url\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\",\"name\":\"Bartling opta por SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2018-10-31T14:23:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/slot-news-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bartling opta por SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bartling opta por SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/","og_locale":"es_ES","og_type":"article","og_title":"Bartling opta por SLOT - Cargoclix","og_description":"La empresa Bartling GmbH &amp; Co. KG es uno de los fabricantes m\u00e1s exitosos de envases a medida para la industria alimentaria. Para optimizar los procesos log\u00edsticos en la rampa, la empresa de Borgholzhausen conf\u00eda en la plataforma de gesti\u00f3n de franjas horarias SLOT de Cargoclix. Aproximadamente 15 camiones son cargados y descargados diariamente en [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2018-10-31T14:23:40+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Bartling opta por SLOT","datePublished":"2018-10-31T14:23:40+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/"},"wordCount":107,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/","url":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/","name":"Bartling opta por SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2018-10-31T14:23:40+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/es\/2018\/10\/31\/bartling-opta-por-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/slot-news-es\/"},{"@type":"ListItem","position":4,"name":"Bartling opta por SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/7911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/comments?post=7911"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/7911\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/media?parent=7911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/categories?post=7911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/tags?post=7911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}