{"id":7734,"date":"2018-10-25T14:11:34","date_gmt":"2018-10-25T14:11:34","guid":{"rendered":"https:\/\/stage-start.cargoclix.com\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/"},"modified":"2018-10-25T14:11:34","modified_gmt":"2018-10-25T14:11:34","slug":"falk-pharma-se-convierte-en-cliente-de-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/","title":{"rendered":"Falk Pharma se convierte en cliente de SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">FALK Pharma GmbH en Friburgo es un nuevo cliente de Cargoclix desde octubre. El fabricante farmac\u00e9utico utiliza el sistema de franjas horarias basado en la web SLOT para una carga y descarga optimizada de camiones en las rampas. Un total de 70 camiones son despachados diariamente en tres rampas de entrada y salida de mercanc\u00edas, cada uno con una asignaci\u00f3n de franjas horarias. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La empresa Dr. Falk Pharma GmbH de Friburgo es l\u00edder del mercado en los campos de la gastroenterolog\u00eda y la hepatolog\u00eda. Adem\u00e1s de Alemania, la mayor\u00eda de los medicamentos recetados se venden en 65 pa\u00edses a trav\u00e9s de nuestras propias filiales de ventas o socios locales.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FALK Pharma GmbH en Friburgo es un nuevo cliente de Cargoclix desde octubre. El fabricante farmac\u00e9utico utiliza el sistema de franjas horarias basado en la web SLOT para una carga y descarga optimizada de camiones en las rampas. Un total de 70 camiones son despachados diariamente en tres rampas de entrada y salida de mercanc\u00edas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[331,292],"tags":[335],"class_list":["post-7734","post","type-post","status-publish","format-standard","hentry","category-company-news-es","category-slot-news-es","tag-slot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Falk Pharma se convierte en cliente de SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falk Pharma se convierte en cliente de SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"FALK Pharma GmbH en Friburgo es un nuevo cliente de Cargoclix desde octubre. El fabricante farmac\u00e9utico utiliza el sistema de franjas horarias basado en la web SLOT para una carga y descarga optimizada de camiones en las rampas. Un total de 70 camiones son despachados diariamente en tres rampas de entrada y salida de mercanc\u00edas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-25T14:11:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Falk Pharma se convierte en cliente de SLOT\",\"datePublished\":\"2018-10-25T14:11:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\",\"url\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\",\"name\":\"Falk Pharma se convierte en cliente de SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2018-10-25T14:11:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/slot-news-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Falk Pharma se convierte en cliente de SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falk Pharma se convierte en cliente de SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/","og_locale":"es_ES","og_type":"article","og_title":"Falk Pharma se convierte en cliente de SLOT - Cargoclix","og_description":"FALK Pharma GmbH en Friburgo es un nuevo cliente de Cargoclix desde octubre. El fabricante farmac\u00e9utico utiliza el sistema de franjas horarias basado en la web SLOT para una carga y descarga optimizada de camiones en las rampas. Un total de 70 camiones son despachados diariamente en tres rampas de entrada y salida de mercanc\u00edas, [&hellip;]","og_url":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2018-10-25T14:11:34+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#article","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Falk Pharma se convierte en cliente de SLOT","datePublished":"2018-10-25T14:11:34+00:00","mainEntityOfPage":{"@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/"},"wordCount":126,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/","url":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/","name":"Falk Pharma se convierte en cliente de SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2018-10-25T14:11:34+00:00","breadcrumb":{"@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/safe-checkin.com\/es\/2018\/10\/25\/falk-pharma-se-convierte-en-cliente-de-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/safe-checkin.com\/es\/category\/company-news-es\/slot-news-es\/"},{"@type":"ListItem","position":4,"name":"Falk Pharma se convierte en cliente de SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/7734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/comments?post=7734"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/7734\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/media?parent=7734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/categories?post=7734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/tags?post=7734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}