{"id":17991,"date":"2022-01-25T15:44:25","date_gmt":"2022-01-25T15:44:25","guid":{"rendered":"https:\/\/start.cargoclix.com\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/"},"modified":"2022-01-25T15:44:25","modified_gmt":"2022-01-25T15:44:25","slug":"zumtobel-da-luz-verde-a-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/","title":{"rendered":"Zumtobel da luz verde a SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La empresa de tecnolog\u00eda de iluminaci\u00f3n Zumtobel, con sede en Dornbirn (Austria), ha introducido el sistema de gesti\u00f3n de franjas horarias basado en la nube SLOT de Cargoclix en su centro de Hohenems, optimizando el env\u00edo diario sin atascos de unos 15 camiones en el departamento de entrada de mercanc\u00edas. Los proveedores de servicios log\u00edsticos que quieran reservar una franja horaria para la entrega all\u00ed pueden hacerlo con un plazo de diez d\u00edas. La \u00faltima opci\u00f3n de reserva es doce horas antes de la fecha deseada. Los costes de reserva por franja horaria son de 50 c\u00e9ntimos. Los proveedores de servicios log\u00edsticos se encargan de ello.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zumtobel ofrece el desarrollo, la fabricaci\u00f3n y la venta de tecnolog\u00eda de iluminaci\u00f3n, as\u00ed como soluciones y componentes de iluminaci\u00f3n para diversas aplicaciones. La empresa coopera con m\u00e1s de 90 oficinas de venta y socios en todo el mundo y emplea a unas 5.800 personas.\u00a0 <\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/es\/slot\/\"><span style=\"font-weight: 400;\">*Cargoclix SLOT. Gesti\u00f3n de franjas horarias y patios<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT optimiza los procesos y el despliegue de personal en la rampa. Evita tiempos de espera y los picos en los puntos de carga y descarga.\u00a0 Nuestro sistema de gesti\u00f3n de franjas horarias tambi\u00e9n garantiza la transparencia de todos los procesos log\u00edsticos. Por lo tanto, es la mejor soluci\u00f3n para la industria, el comercio, los proveedores de servicios log\u00edsticos y las empresas de transporte.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa de tecnolog\u00eda de iluminaci\u00f3n Zumtobel, con sede en Dornbirn (Austria), ha introducido el sistema de gesti\u00f3n de franjas horarias basado en la nube SLOT de Cargoclix en su centro de Hohenems, optimizando el env\u00edo diario sin atascos de unos 15 camiones en el departamento de entrada de mercanc\u00edas. Los proveedores de servicios log\u00edsticos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[331,292],"tags":[335],"class_list":["post-17991","post","type-post","status-publish","format-standard","hentry","category-company-news-es","category-slot-news-es","tag-slot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zumtobel da luz verde a SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zumtobel da luz verde a SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"La empresa de tecnolog\u00eda de iluminaci\u00f3n Zumtobel, con sede en Dornbirn (Austria), ha introducido el sistema de gesti\u00f3n de franjas horarias basado en la nube SLOT de Cargoclix en su centro de Hohenems, optimizando el env\u00edo diario sin atascos de unos 15 camiones en el departamento de entrada de mercanc\u00edas. Los proveedores de servicios log\u00edsticos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T15:44:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Zumtobel da luz verde a SLOT\",\"datePublished\":\"2022-01-25T15:44:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\"},\"wordCount\":247,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\",\"url\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\",\"name\":\"Zumtobel da luz verde a SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2022-01-25T15:44:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/82.165.97.253\/category\/company-news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/safe-checkin.com\/category\/company-news\/slot-news\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Zumtobel da luz verde a SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zumtobel da luz verde a SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/","og_locale":"es_ES","og_type":"article","og_title":"Zumtobel da luz verde a SLOT - Cargoclix","og_description":"La empresa de tecnolog\u00eda de iluminaci\u00f3n Zumtobel, con sede en Dornbirn (Austria), ha introducido el sistema de gesti\u00f3n de franjas horarias basado en la nube SLOT de Cargoclix en su centro de Hohenems, optimizando el env\u00edo diario sin atascos de unos 15 camiones en el departamento de entrada de mercanc\u00edas. Los proveedores de servicios log\u00edsticos [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2022-01-25T15:44:25+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Zumtobel da luz verde a SLOT","datePublished":"2022-01-25T15:44:25+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/"},"wordCount":247,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/","url":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/","name":"Zumtobel da luz verde a SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2022-01-25T15:44:25+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/es\/2022\/01\/25\/zumtobel-da-luz-verde-a-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/es\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/82.165.97.253\/category\/company-news\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/safe-checkin.com\/category\/company-news\/slot-news\/"},{"@type":"ListItem","position":4,"name":"Zumtobel da luz verde a SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/17991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/comments?post=17991"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/17991\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/media?parent=17991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/categories?post=17991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/tags?post=17991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}