{"id":11674,"date":"2020-02-20T09:36:05","date_gmt":"2020-02-20T09:36:05","guid":{"rendered":"https:\/\/start.cargoclix.com\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/"},"modified":"2020-02-20T09:36:05","modified_gmt":"2020-02-20T09:36:05","slug":"cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/","title":{"rendered":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">No importa si es domingo o lunes: a partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios. Los calendarios est\u00e1n disponibles para la selecci\u00f3n de fechas en el programa, en la pesta\u00f1a \u00abReservas\u00bb y en los ajustes de l\u00edmites. Hasta ahora el primer d\u00eda de la semana se determinaba seleccionando el idioma de la interfaz de usuario &#8211; lunes para el alem\u00e1n, domingo para el ingl\u00e9s. Esto es ahora una cosa del pasado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para establecer la selecci\u00f3n, seleccione primero el \u00e1rea Datos maestros en \u00abMi Cargoclix\u00bb y active la edici\u00f3n en el campo \u00abDatos personales\u00bb. Ahora cada usuario puede seleccionar la opci\u00f3n deseada en un men\u00fa desplegable bajo \u00abPrimer d\u00eda de la semana\u00bb y establecer el primer d\u00eda de la semana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-11663\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\" alt=\"\" width=\"300\" height=\"277\" srcset=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png 300w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-768x709.png 768w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-401x370.png 401w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week.png 803w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/es\/slot\/\"><span style=\"font-weight: 400;\">*Cargoclix SLOT. Gesti\u00f3n de franjas horarias y patios<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT optimiza los procesos y el despliegue de personal en la rampa. Evita tiempos de espera y los picos en los puntos de carga y descarga.\u00a0 Nuestro sistema de gesti\u00f3n de franjas horarias tambi\u00e9n garantiza la transparencia de todos los procesos log\u00edsticos. Por lo tanto, es la mejor soluci\u00f3n para la industria, el comercio, los proveedores de servicios log\u00edsticos y las empresas de transporte.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No importa si es domingo o lunes: a partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios. Los calendarios est\u00e1n disponibles para la selecci\u00f3n de fechas en el programa, en la pesta\u00f1a \u00abReservas\u00bb y en los ajustes de l\u00edmites. Hasta ahora el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[309],"tags":[335,334],"class_list":["post-11674","post","type-post","status-publish","format-standard","hentry","category-tech-news-es","tag-slot","tag-tech-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix<\/title>\n<meta name=\"description\" content=\"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-20T09:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana\",\"datePublished\":\"2020-02-20T09:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\",\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\",\"url\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\",\"name\":\"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\",\"datePublished\":\"2020-02-20T09:36:05+00:00\",\"description\":\"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.\",\"breadcrumb\":{\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage\",\"url\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\",\"contentUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/safe-checkin.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/82.165.97.253\/es\/category\/tech-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix","description":"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/","og_locale":"es_ES","og_type":"article","og_title":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix","og_description":"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.","og_url":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2020-02-20T09:36:05+00:00","og_image":[{"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png","type":"","width":"","height":""}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#article","isPartOf":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana","datePublished":"2020-02-20T09:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/"},"wordCount":238,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"image":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png","keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/","url":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/","name":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage"},"image":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png","datePublished":"2020-02-20T09:36:05+00:00","description":"A partir de ahora cada usuario de Cargoclix puede definir por s\u00ed mismo qu\u00e9 d\u00eda de la semana aparece primero en los calendarios.","breadcrumb":{"@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#primaryimage","url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png","contentUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2020\/02\/First-Day-of-the-Week-300x277.png"},{"@type":"BreadcrumbList","@id":"https:\/\/82.165.97.253\/es\/2020\/02\/20\/cargoclix-permite-la-adaptacion-del-primer-dia-de-la-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/safe-checkin.com\/es\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/82.165.97.253\/es\/category\/tech-news-es\/"},{"@type":"ListItem","position":3,"name":"Cargoclix permite la adaptaci\u00f3n del primer d\u00eda de la semana"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/11674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/comments?post=11674"}],"version-history":[{"count":0,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/posts\/11674\/revisions"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/media?parent=11674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/categories?post=11674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/es\/wp-json\/wp\/v2\/tags?post=11674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}