{"id":18751,"date":"2023-01-24T13:29:30","date_gmt":"2023-01-24T13:29:30","guid":{"rendered":"https:\/\/start.cargoclix.com\/?p=18751"},"modified":"2023-01-24T14:07:50","modified_gmt":"2023-01-24T14:07:50","slug":"neue-speicherfunktion-fuer-benutzergruppen","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/","title":{"rendered":"Neue Speicherfunktion f\u00fcr Benutzergruppen"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Cargoclix hat die Funktion zur Pflege der Benutzergruppen im Adminbereich um eine neue Funktion erweitert. Ab sofort haben SLOT-Admins die M\u00f6glichkeit, mehrere \u00c4nderungen vorzunehmen und alle mit einem Klick auf den Button \u201eSpeichern\u201c zu sichern.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der neue Speichern-Button befindet sich oben rechts und ist sowohl im Reiter \u201eRechte Matrix\u201c als auch im Reiter \u201eBenutzer zu Gruppe hinzuf\u00fcgen\u201c verf\u00fcgbar. Der SLOT-Admin kann die gew\u00fcnschten H\u00e4kchen setzen und\/oder entfernen und auf den Button \u201eSpeichern\u201c klicken. Die Cargoclix-Seite l\u00e4dt kurz und die gew\u00fcnschte \u00c4nderung wird gesichert. Auf diese Weise entfallen die Ladezeiten bei jedem Klick und die Verwaltung der Benutzergruppen wird schneller und benutzerfreundlicher.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargoclix hat die Funktion zur Pflege der Benutzergruppen im Adminbereich um eine neue Funktion erweitert. Ab sofort haben SLOT-Admins die M\u00f6glichkeit, mehrere \u00c4nderungen vorzunehmen und alle mit einem Klick auf den Button \u201eSpeichern\u201c zu sichern. Der neue Speichern-Button befindet sich oben rechts und ist sowohl im Reiter \u201eRechte Matrix\u201c als auch im Reiter \u201eBenutzer zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[329,307],"tags":[215],"class_list":["post-18751","post","type-post","status-publish","format-standard","hentry","category-company-news-de","category-tech-news-de","tag-slot-2-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Cargoclix hat die Funktion zur Pflege der Benutzergruppen im Adminbereich um eine neue Funktion erweitert. Ab sofort haben SLOT-Admins die M\u00f6glichkeit, mehrere \u00c4nderungen vorzunehmen und alle mit einem Klick auf den Button \u201eSpeichern\u201c zu sichern. Der neue Speichern-Button befindet sich oben rechts und ist sowohl im Reiter \u201eRechte Matrix\u201c als auch im Reiter \u201eBenutzer zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-24T13:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T14:07:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Neue Speicherfunktion f\u00fcr Benutzergruppen\",\"datePublished\":\"2023-01-24T13:29:30+00:00\",\"dateModified\":\"2023-01-24T14:07:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\"},\"wordCount\":115,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"TECH News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\",\"url\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\",\"name\":\"Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2023-01-24T13:29:30+00:00\",\"dateModified\":\"2023-01-24T14:07:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/82.165.97.253\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/tech-news-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neue Speicherfunktion f\u00fcr Benutzergruppen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/de\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix","og_description":"Cargoclix hat die Funktion zur Pflege der Benutzergruppen im Adminbereich um eine neue Funktion erweitert. Ab sofort haben SLOT-Admins die M\u00f6glichkeit, mehrere \u00c4nderungen vorzunehmen und alle mit einem Klick auf den Button \u201eSpeichern\u201c zu sichern. Der neue Speichern-Button befindet sich oben rechts und ist sowohl im Reiter \u201eRechte Matrix\u201c als auch im Reiter \u201eBenutzer zu [&hellip;]","og_url":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2023-01-24T13:29:30+00:00","article_modified_time":"2023-01-24T14:07:50+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"websitedev","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#article","isPartOf":{"@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Neue Speicherfunktion f\u00fcr Benutzergruppen","datePublished":"2023-01-24T13:29:30+00:00","dateModified":"2023-01-24T14:07:50+00:00","mainEntityOfPage":{"@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/"},"wordCount":115,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","TECH News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/","url":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/","name":"Neue Speicherfunktion f\u00fcr Benutzergruppen - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2023-01-24T13:29:30+00:00","dateModified":"2023-01-24T14:07:50+00:00","breadcrumb":{"@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/safe-checkin.com\/de\/2023\/01\/24\/neue-speicherfunktion-fuer-benutzergruppen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/82.165.97.253\/de\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/tech-news-de\/"},{"@type":"ListItem","position":3,"name":"Neue Speicherfunktion f\u00fcr Benutzergruppen"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/de\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/comments?post=18751"}],"version-history":[{"count":1,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18751\/revisions"}],"predecessor-version":[{"id":18752,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18751\/revisions\/18752"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/media?parent=18751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/categories?post=18751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/tags?post=18751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}