{"id":18163,"date":"2022-03-29T08:03:03","date_gmt":"2022-03-29T08:03:03","guid":{"rendered":"https:\/\/start.cargoclix.com\/?p=18163"},"modified":"2022-03-29T08:03:03","modified_gmt":"2022-03-29T08:03:03","slug":"cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/","title":{"rendered":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine"},"content":{"rendered":"<p><em><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-18164 size-full\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\" alt=\"\" width=\"1000\" height=\"500\" srcset=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg 1000w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1-300x150.jpg 300w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1-768x384.jpg 768w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1-500x250.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/strong><\/em><\/p>\n<ul>\n<li><em><strong>Freiburger Systemhaus stellt seinen Logistikmarktplatz f\u00fcr den Transport von Hilfsg\u00fctern bis auf weiteres kostenlos zur Verf\u00fcgung.<\/strong><\/em><\/li>\n<li><em><strong>Unb\u00fcrokratische Vermittlung von verf\u00fcgbarem Laderaum.<\/strong><\/em><\/li>\n<\/ul>\n<p>(Freiburg i.Br., 22. M\u00e4rz 2022) In diesen Tagen organisieren zahlreiche Hilfsorganisationen, aber auch Privatpersonen und Vereine, spontane Hilfstransporte an die ukrainische Grenze. An Bord haben sie meist Lebensmittel, aber auch dringend ben\u00f6tigte Waren des t\u00e4glichen Bedarfs wie Babywindeln, Kleidung oder Medikamente f\u00fcr die Menschen auf der Flucht. Wer einen solchen Transport organisiert, steht allerdings h\u00e4ufig vor dem Problem, ein passendes Fahrzeug zu finden. Transporter, Lkw und Laderaum sind aktuell knapp, sehr teuer oder \u00fcber l\u00e4ngere Zeit nicht verf\u00fcgbar.<\/p>\n<p>Um den Anbietern von Hilfstransporten die Suche nach verf\u00fcgbarem und g\u00fcnstigem oder im Idealfall sogar kostenlosen Laderaum zu erleichtern, bietet Cargoclix \u00fcber seinen Logistikmarktplatz TENDER ab sofort die M\u00f6glichkeit, solche Transporte kostenlos elektronisch auszuschreiben und Angebote von Speditionen und Frachtf\u00fchrern daf\u00fcr einzuholen. \u201eDer Krieg in der Ukraine hat uns alle ersch\u00fcttert. Mit unserem Angebot wollen wir unb\u00fcrokratisch Hilfe bieten und Hilfsorganisationen mit m\u00f6glichen Anbietern von Laderaum zusammenbringen\u201c, betont Professor Dr. Victor Meier, beratender Gesellschafter bei Cargoclix.<\/p>\n<p>Wer einen Hilfstransport organisieren und das Angebot der kostenlosen Ausschreibung \u00fcber TENDER nutzen m\u00f6chte, kann \u00fcber tender@cargoclix.com, Stichwort \u201eUkraine-Hilfe\u201c, Kontakt zum TENDER-Support aufnehmen. F\u00fcr weitere Informationen steht dar\u00fcber hinaus das Team von Cargoclix TENDER unter +49 (0)761 205511-00 zur Verf\u00fcgung.<\/p>\n<p>Die cloudbasierte Software TENDER, die die Abwicklung weltweiter Ausschreibungen von Kontrakten f\u00fcr Transporte auf der Stra\u00dfe, der Schiene, in der Luft, der See- und Binnenschifffahrt sowie f\u00fcr Kurier-Express-Paketdienstleistungen und Logistikdienste erm\u00f6glicht, zeichnet sich vor allem durch ihre einfache Bedienbarkeit aus.<\/p>\n<p><strong>\u00dcber Cargoclix<\/strong><\/p>\n<p>Cargoclix ist ein neutraler Internetmarktplatz f\u00fcr die elektronische Ausschreibung von Transporten und Logistikleistungen sowie ein Anbieter von modularen Zeitfenstermanagementsystemen.<br \/>\nDie Dienstleistungspalette der Logistikplattform \u201e<a href=\"https:\/\/start.cargoclix.com\/de\/tender\/\" target=\"_blank\" rel=\"noopener\">Cargoclix TENDER<\/a>\u201c umfasst weltweite Ausschreibungen von Kontrakten f\u00fcr Transporte auf Stra\u00dfe, Schiene, Luftfracht, See- und Binnenschifffahrt, Kurier-Express-Paketdienstleistungen sowie Logistikdiensten, wie zum Beispiel Lagerei. Mit \u00fcber 28.000 registrierten Mitgliedern aus Industrie, Handel und Spedition geh\u00f6rt TENDER zu den f\u00fchrenden internationalen Ausschreibungsplattformen f\u00fcr Transport und Logistik.<br \/>\nZentrales Produkt des Gesch\u00e4ftsbereichs Zeitfenstermanagement ist die modular anpassbare Software \u201eCargoclix SLOT\u201c zur Optimierung der Abl\u00e4ufe an der Rampe. Mit mehr als 100.000 Mitgliedern ist SLOT eines der meistgenutzten Zeitfenstermanagementsysteme.<br \/>\nCargoclix ist eine Marke der Dr. Meier &amp; Schmidt GmbH. Das Unternehmen wurde 1998 gegr\u00fcndet und hat seinen Sitz in Freiburg i.Br. www.cargoclix.com<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Freiburger Systemhaus stellt seinen Logistikmarktplatz f\u00fcr den Transport von Hilfsg\u00fctern bis auf weiteres kostenlos zur Verf\u00fcgung. Unb\u00fcrokratische Vermittlung von verf\u00fcgbarem Laderaum. (Freiburg i.Br., 22. M\u00e4rz 2022) In diesen Tagen organisieren zahlreiche Hilfsorganisationen, aber auch Privatpersonen und Vereine, spontane Hilfstransporte an die ukrainische Grenze. An Bord haben sie meist Lebensmittel, aber auch dringend ben\u00f6tigte Waren des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[329,322,297],"tags":[206],"class_list":["post-18163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news-de","category-press-releases-de","category-tender-news-de-2","tag-tender-2-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Freiburger Systemhaus stellt seinen Logistikmarktplatz f\u00fcr den Transport von Hilfsg\u00fctern bis auf weiteres kostenlos zur Verf\u00fcgung. Unb\u00fcrokratische Vermittlung von verf\u00fcgbarem Laderaum. (Freiburg i.Br., 22. M\u00e4rz 2022) In diesen Tagen organisieren zahlreiche Hilfsorganisationen, aber auch Privatpersonen und Vereine, spontane Hilfstransporte an die ukrainische Grenze. An Bord haben sie meist Lebensmittel, aber auch dringend ben\u00f6tigte Waren des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-29T08:03:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine\",\"datePublished\":\"2022-03-29T08:03:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\"},\"wordCount\":423,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\",\"keywords\":[\"TENDER\"],\"articleSection\":[\"Company News\",\"Press Releases\",\"TENDER News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\",\"url\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\",\"name\":\"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\",\"datePublished\":\"2022-03-29T08:03:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage\",\"url\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\",\"contentUrl\":\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/82.165.97.253\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TENDER News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/tender-news-de-2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/de\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/","og_locale":"de_DE","og_type":"article","og_title":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix","og_description":"Freiburger Systemhaus stellt seinen Logistikmarktplatz f\u00fcr den Transport von Hilfsg\u00fctern bis auf weiteres kostenlos zur Verf\u00fcgung. Unb\u00fcrokratische Vermittlung von verf\u00fcgbarem Laderaum. (Freiburg i.Br., 22. M\u00e4rz 2022) In diesen Tagen organisieren zahlreiche Hilfsorganisationen, aber auch Privatpersonen und Vereine, spontane Hilfstransporte an die ukrainische Grenze. An Bord haben sie meist Lebensmittel, aber auch dringend ben\u00f6tigte Waren des [&hellip;]","og_url":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2022-03-29T08:03:03+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg","type":"image\/jpeg"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"websitedev","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#article","isPartOf":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine","datePublished":"2022-03-29T08:03:03+00:00","mainEntityOfPage":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/"},"wordCount":423,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"image":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage"},"thumbnailUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg","keywords":["TENDER"],"articleSection":["Company News","Press Releases","TENDER News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/","url":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/","name":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage"},"image":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage"},"thumbnailUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg","datePublished":"2022-03-29T08:03:03+00:00","breadcrumb":{"@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#primaryimage","url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg","contentUrl":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2022\/03\/Ukraine_Lebensmittel-1000x500-1.jpg","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/safe-checkin.com\/de\/2022\/03\/29\/cargoclix-tender-kostenlose-ausschreibungen-fuer-hilfstransporte-in-die-ukraine-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/82.165.97.253\/de\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/"},{"@type":"ListItem","position":3,"name":"TENDER News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/tender-news-de-2\/"},{"@type":"ListItem","position":4,"name":"Cargoclix TENDER: Kostenlose Ausschreibungen f\u00fcr Hilfstransporte in die Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/de\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/comments?post=18163"}],"version-history":[{"count":1,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18163\/revisions"}],"predecessor-version":[{"id":18170,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/18163\/revisions\/18170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/media\/18164"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/media?parent=18163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/categories?post=18163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/tags?post=18163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}