{"id":16711,"date":"2021-04-12T08:00:01","date_gmt":"2021-04-12T08:00:01","guid":{"rendered":"https:\/\/start.cargoclix.com\/?p=16711"},"modified":"2021-04-14T08:00:47","modified_gmt":"2021-04-14T08:00:47","slug":"raccorderie-metalliche-entscheidet-sich-fuer-slot","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/","title":{"rendered":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Raccorderie Metalliche, einer der weltweit f\u00fchrenden Hersteller von Pressliftings, arbeitet an seinem Hauptsitz im italienischen Campitello di Marcaria im Wareneingang ab sofort mit dem cloudbasierten Zeitfenstermanagementsystem SLOT von Cargoclix. Die cloudbasierte Software sorgt daf\u00fcr, dass rund 20 Lkw pro Tag staufrei abgefertigt werden k\u00f6nnen. Die Frist zur Buchung von Zeitfenstern beginnt 20 Tage im Voraus und endet am Vortag um 23.59 Uhr. Die Buchungskosten von 50 Cent pro Zeitfenster tr\u00e4gt das Unternehmen als Auftraggeber selbst und berechnet die Geb\u00fchr nicht an die Logistikdienstleister weiter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 1970 gegr\u00fcndete Unternehmen fertigt unter anderem Pressfitting-Systeme, Abflusssysteme und Rohrschellen f\u00fcr Zivilanwendungen, Industrie und Schiffbau. Raccorderie Metalliche besch\u00e4ftigt rund 300 Mitarbeiterinnen und Mitarbeiter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">*<\/span><a href=\"https:\/\/start.cargoclix.com\/de\/slot\/\"><span style=\"font-weight: 400;\">Cargoclix SLOT. Das Zeitfenster- und Yard-Management<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT optimiert die Abl\u00e4ufe und den Personaleinsatz an der Rampe und verhindert Wartezeiten und Auslastungsspitzen bei Be- und Entladestellen. Cargoclix kann entweder webbasiert, oder auch voll integriert in ERP- und WMS-Systeme betrieben werden. Cargoclix SLOT er\u00f6ffnet Transparenz \u00fcber alle abgebildeten Logistikprozesse \u2013 f\u00fcr Industrie, Handel, Logistikdienstleister und Transportunternehmen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raccorderie Metalliche, einer der weltweit f\u00fchrenden Hersteller von Pressliftings, arbeitet an seinem Hauptsitz im italienischen Campitello di Marcaria im Wareneingang ab sofort mit dem cloudbasierten Zeitfenstermanagementsystem SLOT von Cargoclix. Die cloudbasierte Software sorgt daf\u00fcr, dass rund 20 Lkw pro Tag staufrei abgefertigt werden k\u00f6nnen. Die Frist zur Buchung von Zeitfenstern beginnt 20 Tage im Voraus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[329,293],"tags":[215],"class_list":["post-16711","post","type-post","status-publish","format-standard","hentry","category-company-news-de","category-slot-news-de","tag-slot-2-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Raccorderie Metalliche, einer der weltweit f\u00fchrenden Hersteller von Pressliftings, arbeitet an seinem Hauptsitz im italienischen Campitello di Marcaria im Wareneingang ab sofort mit dem cloudbasierten Zeitfenstermanagementsystem SLOT von Cargoclix. Die cloudbasierte Software sorgt daf\u00fcr, dass rund 20 Lkw pro Tag staufrei abgefertigt werden k\u00f6nnen. Die Frist zur Buchung von Zeitfenstern beginnt 20 Tage im Voraus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-12T08:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-14T08:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT\",\"datePublished\":\"2021-04-12T08:00:01+00:00\",\"dateModified\":\"2021-04-14T08:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\",\"url\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\",\"name\":\"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"datePublished\":\"2021-04-12T08:00:01+00:00\",\"dateModified\":\"2021-04-14T08:00:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/82.165.97.253\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/slot-news-de\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/de\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/","og_locale":"de_DE","og_type":"article","og_title":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix","og_description":"Raccorderie Metalliche, einer der weltweit f\u00fchrenden Hersteller von Pressliftings, arbeitet an seinem Hauptsitz im italienischen Campitello di Marcaria im Wareneingang ab sofort mit dem cloudbasierten Zeitfenstermanagementsystem SLOT von Cargoclix. Die cloudbasierte Software sorgt daf\u00fcr, dass rund 20 Lkw pro Tag staufrei abgefertigt werden k\u00f6nnen. Die Frist zur Buchung von Zeitfenstern beginnt 20 Tage im Voraus [&hellip;]","og_url":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2021-04-12T08:00:01+00:00","article_modified_time":"2021-04-14T08:00:47+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"websitedev","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#article","isPartOf":{"@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT","datePublished":"2021-04-12T08:00:01+00:00","dateModified":"2021-04-14T08:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/"},"wordCount":174,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/","url":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/","name":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"datePublished":"2021-04-12T08:00:01+00:00","dateModified":"2021-04-14T08:00:47+00:00","breadcrumb":{"@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/safe-checkin.com\/de\/2021\/04\/12\/raccorderie-metalliche-entscheidet-sich-fuer-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/82.165.97.253\/de\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/company-news-de\/slot-news-de\/"},{"@type":"ListItem","position":4,"name":"Raccorderie Metalliche entscheidet sich f\u00fcr SLOT"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/de\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/16711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/comments?post=16711"}],"version-history":[{"count":1,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/16711\/revisions"}],"predecessor-version":[{"id":16712,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/16711\/revisions\/16712"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/media?parent=16711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/categories?post=16711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/tags?post=16711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}