{"id":10189,"date":"2019-09-16T06:40:12","date_gmt":"2019-09-16T06:40:12","guid":{"rendered":"https:\/\/start.cargoclix.com\/?p=10189"},"modified":"2020-06-24T07:57:52","modified_gmt":"2020-06-24T07:57:52","slug":"einstellungsmoeglichkeit-fuer-die-kommentar-felder","status":"publish","type":"post","link":"https:\/\/safe-checkin.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/","title":{"rendered":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Die Standardfelder \u201eKommentar\u201c und \u201eKommentar des Auftraggebers\u201c k\u00f6nnen ab sofort f\u00fcr jede Rampe in puncto Sichtbarkeit und Editierbarkeit angepasst werden. Der CargoMarket Admin kann definieren, welche Benutzerrollen Kommentare eintragen oder einsehen k\u00f6nnen. Es wird mehr Transparenz geschaffen, weil Nutzer mit Rollen, die bis jetzt keinen Zugriff zu den Kommentarfeldern hatten, diese jetzt bearbeiten k\u00f6nnen. Beispiel: Der Rolle \u201eGate\u201c kann erlaubt werden, interne Kommentare einzutragen oder auch dem buchenden Unternehmen Kommentare zu hinterlassen. Es geht aber auch anders herum: Die Kommentare k\u00f6nnen f\u00fcr alle Rollen deaktiviert werden. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Der CargoMarket Admin kann die Felder hier konfigurieren:\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mein Cargoclix &gt; Zeitfenster &gt; Rampen &gt; [Rampe w\u00e4hlen ]&gt; Buchungsdaten &gt; [Einstellungen vom Feld Kommentar oder Kommentar der Auftraggebers \u00fcber den Link \u201ehinzuf\u00fcgen\u201c aufmachen] &gt; dann einen Haken je Rolle f\u00fcr \u201esichtbar f\u00fcr\u201c und \u201ebearbeiten durch\u201c setzen.<\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-10190\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\" alt=\"\" width=\"800\" height=\"445\" srcset=\"https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png 300w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/09\/Comment-function-768x427.png 768w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/09\/Comment-function-1024x570.png 1024w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/09\/Comment-function-762x424.png 762w, https:\/\/safe-checkin.com\/wp-content\/uploads\/2019\/09\/Comment-function.png 1524w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">*<\/span><a href=\"https:\/\/start.cargoclix.com\/de\/slot\/\"><span style=\"font-weight: 400;\">Cargoclix SLOT. Das Zeitfenster- und Yard-Management<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT optimiert die Abl\u00e4ufe und den Personaleinsatz an der Rampe und verhindert Wartezeiten und Auslastungsspitzen bei Be- und Entladestellen. Cargoclix kann entweder webbasiert, oder auch voll integriert in ERP- und WMS-Systeme betrieben werden. Cargoclix SLOT er\u00f6ffnet Transparenz \u00fcber alle abgebildeten Logistikprozesse \u2013 f\u00fcr Industrie, Handel, Logistikdienstleister und Transportunternehmen.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Standardfelder \u201eKommentar\u201c und \u201eKommentar des Auftraggebers\u201c k\u00f6nnen ab sofort f\u00fcr jede Rampe in puncto Sichtbarkeit und Editierbarkeit angepasst werden. Der CargoMarket Admin kann definieren, welche Benutzerrollen Kommentare eintragen oder einsehen k\u00f6nnen. Es wird mehr Transparenz geschaffen, weil Nutzer mit Rollen, die bis jetzt keinen Zugriff zu den Kommentarfeldern hatten, diese jetzt bearbeiten k\u00f6nnen. Beispiel: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[307],"tags":[215,214],"class_list":["post-10189","post","type-post","status-publish","format-standard","hentry","category-tech-news-de","tag-slot-2-de","tag-tech-news-2-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Die Standardfelder \u201eKommentar\u201c und \u201eKommentar des Auftraggebers\u201c k\u00f6nnen ab sofort f\u00fcr jede Rampe in puncto Sichtbarkeit und Editierbarkeit angepasst werden. Der CargoMarket Admin kann definieren, welche Benutzerrollen Kommentare eintragen oder einsehen k\u00f6nnen. Es wird mehr Transparenz geschaffen, weil Nutzer mit Rollen, die bis jetzt keinen Zugriff zu den Kommentarfeldern hatten, diese jetzt bearbeiten k\u00f6nnen. Beispiel: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-16T06:40:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-24T07:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder\",\"datePublished\":\"2019-09-16T06:40:12+00:00\",\"dateModified\":\"2020-06-24T07:57:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\",\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\",\"url\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\",\"name\":\"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\",\"datePublished\":\"2019-09-16T06:40:12+00:00\",\"dateModified\":\"2020-06-24T07:57:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage\",\"url\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\",\"contentUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/82.165.97.253\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/mail.savoiedecision.com\/de\/category\/tech-news-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#website\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safe-checkin.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/safe-checkin.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/safe-checkin.com\/de\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/","og_locale":"de_DE","og_type":"article","og_title":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix","og_description":"Die Standardfelder \u201eKommentar\u201c und \u201eKommentar des Auftraggebers\u201c k\u00f6nnen ab sofort f\u00fcr jede Rampe in puncto Sichtbarkeit und Editierbarkeit angepasst werden. Der CargoMarket Admin kann definieren, welche Benutzerrollen Kommentare eintragen oder einsehen k\u00f6nnen. Es wird mehr Transparenz geschaffen, weil Nutzer mit Rollen, die bis jetzt keinen Zugriff zu den Kommentarfeldern hatten, diese jetzt bearbeiten k\u00f6nnen. Beispiel: [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-09-16T06:40:12+00:00","article_modified_time":"2020-06-24T07:57:52+00:00","og_image":[{"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png","type":"","width":"","height":""}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"websitedev","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/"},"author":{"name":"websitedev","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder","datePublished":"2019-09-16T06:40:12+00:00","dateModified":"2020-06-24T07:57:52+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/"},"wordCount":206,"publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"image":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png","keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/","url":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/","name":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder - Cargoclix","isPartOf":{"@id":"https:\/\/safe-checkin.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage"},"image":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png","datePublished":"2019-09-16T06:40:12+00:00","dateModified":"2020-06-24T07:57:52+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#primaryimage","url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png","contentUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Comment-function-300x167.png"},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/de\/2019\/09\/16\/einstellungsmoeglichkeit-fuer-die-kommentar-felder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/82.165.97.253\/de\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/mail.savoiedecision.com\/de\/category\/tech-news-de\/"},{"@type":"ListItem","position":3,"name":"Einstellungsm\u00f6glichkeit f\u00fcr die Kommentar-Felder"}]},{"@type":"WebSite","@id":"https:\/\/safe-checkin.com\/es\/#website","url":"https:\/\/safe-checkin.com\/es\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/safe-checkin.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safe-checkin.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/safe-checkin.com\/es\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/safe-checkin.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/safe-checkin.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/safe-checkin.com\/de\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/10189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/comments?post=10189"}],"version-history":[{"count":2,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/10189\/revisions"}],"predecessor-version":[{"id":10197,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/posts\/10189\/revisions\/10197"}],"wp:attachment":[{"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/media?parent=10189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/categories?post=10189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safe-checkin.com\/de\/wp-json\/wp\/v2\/tags?post=10189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}